{"id":21545,"date":"2022-06-29T16:47:00","date_gmt":"2022-06-29T16:47:00","guid":{"rendered":"https:\/\/discountkeys.net\/ms-office-2021-st\/"},"modified":"2026-03-16T15:50:19","modified_gmt":"2026-03-16T14:50:19","slug":"o21s","status":"publish","type":"post","link":"https:\/\/manuals.winandoffice.de\/pt\/o21s\/","title":{"rendered":"MS Microsoft Office 2021 Standard"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21545\" class=\"elementor elementor-21545\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a82894a e-flex e-con-boxed e-con e-parent\" data-id=\"1a82894a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6d69fe81 e-con-full e-flex e-con e-child\" data-id=\"6d69fe81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3025136a e-con-full sticky-sidebar e-flex e-con e-child\" data-id=\"3025136a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7eb83c54 e-con-full e-flex e-con e-child\" data-id=\"7eb83c54\" data-element_type=\"container\" data-e-type=\"container\" id=\"mobile-menu\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd636d elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dd636d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#download\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cloud-download-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">DESCARREGAR<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#system\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-desktop\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">REQUISITOS DO SISTEMA<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#installation\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cogs\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">INSTALA\u00c7\u00c3O<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#license\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-key\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">LICEN\u00c7A E ACTIVA\u00c7\u00c3O<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#language\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-language\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TRANSFER\u00caNCIAS NOUTRAS L\u00cdNGUAS<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#note\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-edit\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">NOTA<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c0333cc e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"3c0333cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3303562d elementor-widget elementor-widget-shortcode\" data-id=\"3303562d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div class=\"slider-ad\">\n\t\t\t\t\t                <div class=\"mySlides2 w3-container w3-red\">\n                    <div class=\"wrapper-slider\">\n                        <a href=\"https:\/\/winandoffice.de\/product\/microsoft-office-2024-professional-plus-license-for-3-devices\/\" target=\"_blank\" rel=\"noopener\">\n                            <img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium aligncenter\" src=\"https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/09\/O24P-1.png\" width=\"600\" height=\"600\" \/>\n                        <\/a>\n                        <h6 style=\"text-align: center;\">\n                            <a href=\"https:\/\/winandoffice.de\/product\/microsoft-office-2024-professional-plus-license-for-3-devices\/\" target=\"_blank\" rel=\"noopener\">\n                                Microsoft Office 2024 Licen\u00e7a Professional Plus para 3 dispositivos                            <\/a>\n                        <\/h6>\n                    <\/div>\n                <\/div>\n                            <div class=\"mySlides2 w3-container w3-red\">\n                    <div class=\"wrapper-slider\">\n                        <a href=\"https:\/\/winandoffice.de\/product\/microsoft-windows-11-professional-license-for-3-pcs\/\" target=\"_blank\" rel=\"noopener\">\n                            <img decoding=\"async\" class=\"alignnone size-medium aligncenter\" src=\"https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/09\/W11P-1.png\" width=\"600\" height=\"600\" \/>\n                        <\/a>\n                        <h6 style=\"text-align: center;\">\n                            <a href=\"https:\/\/winandoffice.de\/product\/microsoft-windows-11-professional-license-for-3-pcs\/\" target=\"_blank\" rel=\"noopener\">\n                                Licen\u00e7a do Microsoft Windows 11 Professional para 3 PCs                            <\/a>\n                        <\/h6>\n                    <\/div>\n                <\/div>\n            \t\t\t\t<\/div>\n\t\n\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fd9f1a1 e-con-full e-flex e-con e-child\" data-id=\"1fd9f1a1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-638be4d9 e-con-full e-flex e-con e-child\" data-id=\"638be4d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53416c86 elementor-widget elementor-widget-heading\" data-id=\"53416c86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\nGuia de instala\u00e7\u00e3o Microsoft Office 2021 Standard -32 e 64 Bits<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f1c1f2f e-con-full e-flex e-con e-child\" data-id=\"3f1c1f2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-183d85a3 e-con-full e-flex e-con e-child\" data-id=\"183d85a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dc88d29 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4dc88d29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12e3cf73 e-con-full e-flex e-con e-child\" data-id=\"12e3cf73\" data-element_type=\"container\" data-e-type=\"container\" id=\"download\">\n\t\t<div class=\"elementor-element elementor-element-4108dd57 e-con-full e-flex e-con e-child\" data-id=\"4108dd57\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40bb1b72 elementor-widget elementor-widget-heading\" data-id=\"40bb1b72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DESCARREGAR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7389ac21 elementor-widget elementor-widget-text-editor\" data-id=\"7389ac21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"mnls\">Download o programa com o seguinte link de download<\/p>\n<div style=\"text-align: center;\"><a class=\"mbutton\" href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/PT\/Office_2021_PT_standard_64Bits.exe\">DESCARREGAR<\/a><\/div>\n<p>&nbsp;<\/p>\n<p class=\"mnls\" style=\"font-style: italic; font-size: 0.8em; text-align: center;\">Se precisar do instalador noutro idioma ou noutra vers\u00e3o, <a href=\"#language\">clique aqui<\/a>.<\/p>\n<p class=\"mnls\">Este ficheiro EXE \u00e9 a base para a instala\u00e7\u00e3o do produto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-126492eb e-con-full e-flex e-con e-child\" data-id=\"126492eb\" data-element_type=\"container\" data-e-type=\"container\" id=\"system\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-77f9e56 e-con-full e-flex e-con e-child\" data-id=\"77f9e56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7eb0c83b elementor-widget elementor-widget-heading\" data-id=\"7eb0c83b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">REQUISITOS DO SISTEMA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d36b72b elementor-widget elementor-widget-text-editor\" data-id=\"5d36b72b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Certifique-se de que o seu computador cumpre os requisitos m\u00ednimos do sistema para instalar este software:<\/b><\/p>\n<ul style=\"list-style-type: circle; padding-left: 30px;\">\n<li>Processador de 1 gigahertz (GHz) ou mais r\u00e1pido de 32 bits (x86) ou 64 bits (x64)<\/li>\n<li>1 gigabyte (GB) de RAM (32 bits) ou 4 GB de RAM (64 bits)<\/li>\n<li>4 GB de espa\u00e7o dispon\u00edvel no disco r\u00edgido<\/li>\n<li>Dispositivo gr\u00e1fico DirectX 9 com controlador WDDM 1.0 ou superior<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73c4b8b8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"73c4b8b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16458933 e-flex e-con-boxed e-con e-child\" data-id=\"16458933\" data-element_type=\"container\" data-e-type=\"container\" id=\"installation\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1e4fd3e6 e-con-full e-flex e-con e-child\" data-id=\"1e4fd3e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-347e4bae elementor-widget elementor-widget-heading\" data-id=\"347e4bae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">INSTALA\u00c7\u00c3O<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-500f7ca elementor-widget elementor-widget-text-editor\" data-id=\"500f7ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Antes de instalar, certifique-se de que todas as vers\u00f5es anteriores do Microsoft Office foram removidas e reinicie o seu computador. <\/b>Pode consultar este<span style=\"color: #3366ff;\"><em><strong><a style=\"color: #3366ff;\" href=\"https:\/\/support.microsoft.com\/en-us\/windows\/uninstall-or-remove-apps-and-programs-in-windows-4b55f974-2cc6-2d2b-d092-5905080eaf98\">\u00a0documento de ajuda da Microsoft<\/a> <\/strong><\/em><\/span>caso necessite de ajuda neste passo.<\/p>\n<p><b>Quando a transfer\u00eancia estiver conclu\u00edda, siga estes passos:\u00a0<\/b><\/p>\n\n<p>1. Localize o ficheiro de instala\u00e7\u00e3o descarregado (normalmente est\u00e1 localizado na sua pasta Downloads). Clique com o bot\u00e3o direito do rato no ficheiro e selecione \u201cExecutar como administrador\u201d. Ser-lhe-\u00e1 perguntado se pretende que a aplica\u00e7\u00e3o fa\u00e7a altera\u00e7\u00f5es no seu dispositivo. Clique em \u201cSim\u201d.<\/p>\n<p>Importante: \u00e9 necess\u00e1rio estar online para concluir a instala\u00e7\u00e3o, uma vez que o instalador ir\u00e1 descarregar os ficheiros necess\u00e1rios diretamente da Microsoft.<\/p>\n\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-114057\" src=\"https:\/\/manuals.winandoffice.com\/wp-content\/uploads\/2025\/03\/2021_EN.png\" alt=\"\" width=\"1049\" height=\"795\" srcset=\"https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN.png 1049w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN-300x227.png 300w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN-1024x776.png 1024w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN-768x582.png 768w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN-16x12.png 16w\" sizes=\"(max-width: 1049px) 100vw, 1049px\" \/><\/p>\n\t<p>2. Depois de dar permiss\u00e3o para as altera\u00e7\u00f5es, o produto ser\u00e1 instalado.<br \/>\n<br \/>\n<\/p>\n\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-114053\" src=\"https:\/\/manuals.winandoffice.com\/wp-content\/uploads\/2025\/03\/2021_EN_SD.png\" alt=\"\" width=\"1043\" height=\"784\" srcset=\"https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_SD.png 1043w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_SD-300x226.png 300w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_SD-1024x770.png 1024w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_SD-768x577.png 768w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_SD-16x12.png 16w\" sizes=\"(max-width: 1043px) 100vw, 1043px\" \/><\/p>\n<div>\u00a03. Quando a transfer\u00eancia estiver conclu\u00edda e a instala\u00e7\u00e3o do programa estiver conclu\u00edda, abra qualquer aplica\u00e7\u00e3o do Office e aceda a <b>Conta <\/b>no canto inferior esquerdo. Em seguida, clique em <b>Alterar a chave do produto<\/b> \u00e0 direita, por baixo dos \u00edcones do Office.<\/div>\n<div>\u00a0<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-114052\" src=\"https:\/\/manuals.winandoffice.com\/wp-content\/uploads\/2025\/03\/2021_EN_SD_1.png\" alt=\"\" width=\"1043\" height=\"788\" srcset=\"https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_SD_1.png 1043w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_SD_1-300x227.png 300w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_SD_1-1024x774.png 1024w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_SD_1-768x580.png 768w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_SD_1-16x12.png 16w\" sizes=\"(max-width: 1043px) 100vw, 1043px\" \/><\/p>\n<p>4. Introduza a chave de ativa\u00e7\u00e3o que recebeu por correio eletr\u00f3nico. A sua c\u00f3pia do Microsoft Office 2021 est\u00e1 agora activada.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-114054\" src=\"https:\/\/manuals.winandoffice.com\/wp-content\/uploads\/2025\/03\/2021_EN_3.png\" alt=\"\" width=\"1039\" height=\"776\" srcset=\"https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_3.png 1039w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_3-300x224.png 300w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_3-1024x765.png 1024w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_3-768x574.png 768w, https:\/\/manuals.winandoffice.de\/wp-content\/uploads\/2025\/03\/2021_EN_3-16x12.png 16w\" sizes=\"(max-width: 1039px) 100vw, 1039px\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76482d5d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"76482d5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cc1a0ec e-con-full e-flex e-con e-child\" data-id=\"3cc1a0ec\" data-element_type=\"container\" data-e-type=\"container\" id=\"license\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-285dd802 e-con-full e-flex e-con e-child\" data-id=\"285dd802\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-705ea9f9 elementor-widget elementor-widget-heading\" data-id=\"705ea9f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LICEN\u00c7A E ACTIVA\u00c7\u00c3O<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75036502 elementor-widget elementor-widget-text-editor\" data-id=\"75036502\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lembre-se de que a chave que adquiriu \u00e9 um c\u00f3digo pr\u00e9-pago que n\u00e3o \u00e9 compat\u00edvel com o software pr\u00e9-instalado. Este \u00e9 um produto original da Microsoft. Desinstale a vers\u00e3o anterior do Microsoft Office que tem no seu PC e reinicie o computador. Isto \u00e9 importante para evitar problemas de compatibilidade.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f23d258 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5f23d258\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c757ff1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3c757ff1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42c7423f e-con-full e-flex e-con e-child\" data-id=\"42c7423f\" data-element_type=\"container\" data-e-type=\"container\" id=\"language\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-55faa5cb e-con-full e-flex e-con e-child\" data-id=\"55faa5cb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13beb0e7 elementor-widget elementor-widget-heading\" data-id=\"13beb0e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-family: Roboto, sans-serif;font-size: 26px;font-style: normal\">DOWNLOADS EM<\/span><span style=\"font-family: Roboto, sans-serif;font-size: 26px;font-style: normal\">&nbsp;<\/span><span style=\"font-family: Roboto, sans-serif;font-size: 26px;font-style: normal\">OUTRAS L\u00cdNGUAS<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f44e22a elementor-widget elementor-widget-text-editor\" data-id=\"7f44e22a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"mnls\">Download o programa com o seguinte link de download<\/p>\n<div style=\"width: 100%; text-align: center;\" data-no-translation=\"\">\n<table id=\"downloads\" style=\"width: 80%; margin: 0 auto; border-collapse: collapse;\" border=\"1\">\n<thead>\n<tr>\n<td style=\"width: 40%;\"><b>LANGUAGE<\/b><\/td>\n<td style=\"width: 30%;\"><b>64 BITS<\/b><\/td>\n<td style=\"width: 30%;\"><b>32 BITS<\/b><\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>DEUTSCH<\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/DE\/Office_2021_DE_standard_64Bits.exe\">Herunterladen<\/a><\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/DE\/Office_2021_DE_standard_32Bits.exe\">Herunterladen<\/a><\/td>\n<\/tr>\n<tr>\n<td>ENGLISH<\/td>\n<td><a href=\"\/\/download.winandoffice.com\/Volume\/office\/2021\/EN\/Office_2021_EN_standard_64Bits.exe\">Download<\/a><\/td>\n<td><a href=\"\/\/download.winandoffice.com\/Volume\/office\/2021\/EN\/Office_2021_EN_standard_32Bits.exe\">Download<\/a><\/td>\n<\/tr>\n<tr>\n<td>FRAN\u00c7AIS<\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/FR\/Office_2021_FR_standard_64Bits.exe\">T\u00e9l\u00e9charger<\/a><\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/FR\/Office_2021_FR_standard_32Bits.exe\">T\u00e9l\u00e9charger<\/a><\/td>\n<\/tr>\n<tr>\n<td>ITALIANO<\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/IT\/Office_2021_IT_standard_64Bits.exe\">Scarica<\/a><\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/IT\/Office_2021_IT_standard_32Bits.exe\">Scarica<\/a><\/td>\n<\/tr>\n<tr>\n<td>ESPA\u00d1OL<\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/ES\/Office_2021_ES_standard_64Bits.exe\">Descargar<\/a><\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/ES\/Office_2021_ES_standard_32Bits.exe\">Descargar<\/a><\/td>\n<\/tr>\n<tr>\n<td>FINNISH<\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/FI\/Office_2021_FI_standard_64Bits.exe\">Lataa<\/a><\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/FI\/Office_2021_FI_standard_32Bits.exe\">Lataa<\/a><\/td>\n<\/tr>\n<tr>\n<td>NORWEGIAN<\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/NO\/Office_2021_NO_standard_64Bits.exe\">Last Ned<\/a><\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/NO\/Office_2021_NO_standard_32Bits.exe\">Last Ned<\/a><\/td>\n<\/tr>\n<tr>\n<td>SWEDISH<\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/SV\/Office_2021_SV_standard_64Bits.exe\">Download<\/a><\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/SV\/Office_2021_SV_standard_32Bits.exe\">Download<\/a><\/td>\n<\/tr>\n<tr>\n<td>DANISH<\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/DA\/Office_2021_DA_standard_64Bits.exe\">Download<\/a><\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/DA\/Office_2021_DA_standard_32Bits.exe\">Download<\/a><\/td>\n<\/tr>\n<tr>\n<td>\u0395\u03bb\u03bb\u03ac\u03b4\u03b1<\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/GR\/Office_2021_GR_standard_64Bits.exe\">\u039b\u03ae\u03c8\u03b7<\/a><\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/GR\/Office_2021_GR_standard_64Bits.exe\">\u039b\u03ae\u03c8\u03b7<\/a><\/td>\n<\/tr>\n<tr>\n<td>PORTUGUES<\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/PT\/Office_2021_PT_standard_64Bits.exe\">Descarregar<\/a><\/td>\n<td><a href=\"https:\/\/download.winandoffice.com\/Volume\/office\/2021\/PT\/Office_2021_PT_standard_64Bits.exe\">Descarregar<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p class=\"mnls\"> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-199aac3a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"199aac3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d313dea e-con-full e-flex e-con e-child\" data-id=\"3d313dea\" data-element_type=\"container\" data-e-type=\"container\" id=\"note\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5261b76 e-con-full e-flex e-con e-child\" data-id=\"5261b76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67f44976 elementor-widget elementor-widget-heading\" data-id=\"67f44976\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NOTA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42d0930f elementor-widget elementor-widget-text-editor\" data-id=\"42d0930f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"mnls\">A Microsoft tem vindo a eliminar gradualmente o suporte para alguns produtos mais antigos. Por conseguinte, a ativa\u00e7\u00e3o por telefone j\u00e1 n\u00e3o \u00e9 poss\u00edvel. Se tiver algum problema ou d\u00favida durante a instala\u00e7\u00e3o, contacte o nosso servi\u00e7o de apoio ao cliente 24 horas por dia, 7 dias por semana.<\/p><p class=\"mnls\">Para uma assist\u00eancia mais r\u00e1pida, pode tamb\u00e9m contactar-nos diretamente atrav\u00e9s do nosso chat ao vivo, dispon\u00edvel 24 horas por dia, 7 dias por semana, no nosso s\u00edtio Web.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>DOWNLOAD SYSTEM REQUIREMENTS INSTALLATION LICENSE AND ACTIVATION DOWNLOADS IN OTHER LANGUAGES NOTE Installation guide Microsoft Office 2021 Standard -32 &amp; 64 Bits DOWNLOAD Download the program with the following download link DOWNLOAD &nbsp; If you need the installer in another language or another version, click here. This EXE file is&hellip; <\/p>","protected":false},"author":7015,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,18],"tags":[],"class_list":["post-21545","post","type-post","status-publish","format-standard","hentry","category-esd","category-ms-office"],"acf":[],"_links":{"self":[{"href":"https:\/\/manuals.winandoffice.de\/pt\/wp-json\/wp\/v2\/posts\/21545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manuals.winandoffice.de\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manuals.winandoffice.de\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manuals.winandoffice.de\/pt\/wp-json\/wp\/v2\/users\/7015"}],"replies":[{"embeddable":true,"href":"https:\/\/manuals.winandoffice.de\/pt\/wp-json\/wp\/v2\/comments?post=21545"}],"version-history":[{"count":0,"href":"https:\/\/manuals.winandoffice.de\/pt\/wp-json\/wp\/v2\/posts\/21545\/revisions"}],"wp:attachment":[{"href":"https:\/\/manuals.winandoffice.de\/pt\/wp-json\/wp\/v2\/media?parent=21545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manuals.winandoffice.de\/pt\/wp-json\/wp\/v2\/categories?post=21545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manuals.winandoffice.de\/pt\/wp-json\/wp\/v2\/tags?post=21545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}